{"id":4407,"date":"2022-10-25T13:48:54","date_gmt":"2022-10-25T11:48:54","guid":{"rendered":"http:\/\/albergueweb1.uva.es\/catedra-sindicalismo-dialogo-social\/?p=4407"},"modified":"2022-10-25T13:48:54","modified_gmt":"2022-10-25T11:48:54","slug":"conferencia-la-contribucion-del-sindicalismo-a-la-transicion-politica-espanola","status":"publish","type":"post","link":"https:\/\/albergueweb1.uva.es\/catedra-sindicalismo-dialogo-social\/index.php\/2022\/10\/25\/conferencia-la-contribucion-del-sindicalismo-a-la-transicion-politica-espanola\/","title":{"rendered":"CONFERENCIA: LA CONTRIBUCI\u00d3N DEL SINDICALISMO A LA TRANSICI\u00d3N POL\u00cdTICA ESPA\u00d1OLA"},"content":{"rendered":"<div class=\"wpb-content-wrapper\">[vc_row][vc_column][vc_column_text]<img loading=\"lazy\" decoding=\"async\" class=\"wp-image-4408 size-full aligncenter\" src=\"https:\/\/albergueweb1.uva.es\/catedra-sindicalismo-dialogo-social\/wp-content\/uploads\/2022\/10\/conferencia-Manuela-Aroca-28-oct-2022.jpg\" alt=\"\" width=\"850\" height=\"1100\" srcset=\"https:\/\/albergueweb1.uva.es\/catedra-sindicalismo-dialogo-social\/wp-content\/uploads\/2022\/10\/conferencia-Manuela-Aroca-28-oct-2022.jpg 850w, https:\/\/albergueweb1.uva.es\/catedra-sindicalismo-dialogo-social\/wp-content\/uploads\/2022\/10\/conferencia-Manuela-Aroca-28-oct-2022-618x800.jpg 618w, https:\/\/albergueweb1.uva.es\/catedra-sindicalismo-dialogo-social\/wp-content\/uploads\/2022\/10\/conferencia-Manuela-Aroca-28-oct-2022-768x994.jpg 768w\" sizes=\"auto, (max-width: 850px) 100vw, 850px\" \/>[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column width=\u00bb1\/2&#8243;][vc_btn title=\u00bbDESCARGAR CARTEL.\u00bb color=\u00bbpurple\u00bb size=\u00bblg\u00bb align=\u00bbcenter\u00bb button_block=\u00bbtrue\u00bb link=\u00bburl:http%3A%2F%2Falbergueweb1.uva.es%2Fcatedra-sindicalismo-dialogo-social%2Fwp-content%2Fuploads%2F2022%2F10%2Fconferencia-Manuela-Aroca-28-oct-2022.pdf|title:DESCARGAR%20CARTEL.|target:_blank\u00bb][\/vc_column][vc_column width=\u00bb1\/2&#8243;][vc_btn title=\u00bbASISTENCIA VIRTUAL. ENLACE.\u00bb color=\u00bbpurple\u00bb size=\u00bblg\u00bb align=\u00bbcenter\u00bb button_block=\u00bbtrue\u00bb link=\u00bburl:https%3A%2F%2Feu.bbcollab.com%2Fcollab%2Fui%2Fsession%2Fguest%2F975f8900962946f1ba5a1626d27e187b|title:ASISTENCIA%20VIRTUAL|target:_blank\u00bb][\/vc_column][\/vc_row]\n<\/div>","protected":false},"excerpt":{"rendered":"[vc_row][vc_column][vc_column_text][\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column width=\u00bb1\/2&#8243;][vc_btn title=\u00bbDESCARGAR CARTEL.\u00bb color=\u00bbpurple\u00bb size=\u00bblg\u00bb align=\u00bbcenter\u00bb button_block=\u00bbtrue\u00bb link=\u00bburl:http%3A%2F%2Falbergueweb1.uva.es%2Fcatedra-sindicalismo-dialogo-social%2Fwp-content%2Fuploads%2F2022%2F10%2Fconferencia-Manuela-Aroca-28-oct-2022.pdf|title:DESCARGAR%20CARTEL.|target:_blank\u00bb][\/vc_column][vc_column width=\u00bb1\/2&#8243;][vc_btn title=\u00bbASISTENCIA VIRTUAL. ENLACE.\u00bb color=\u00bbpurple\u00bb size=\u00bblg\u00bb align=\u00bbcenter\u00bb button_block=\u00bbtrue\u00bb link=\u00bburl:https%3A%2F%2Feu.bbcollab.com%2Fcollab%2Fui%2Fsession%2Fguest%2F975f8900962946f1ba5a1626d27e187b|title:ASISTENCIA%20VIRTUAL|target:_blank\u00bb][\/vc_column][\/vc_row]\n","protected":false},"author":1,"featured_media":4408,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[37,17,38],"tags":[],"class_list":["post-4407","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-37","category-actividades","category-jornada-de-clausura"],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 12:33:58","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/albergueweb1.uva.es\/catedra-sindicalismo-dialogo-social\/index.php\/wp-json\/wp\/v2\/posts\/4407","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/albergueweb1.uva.es\/catedra-sindicalismo-dialogo-social\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/albergueweb1.uva.es\/catedra-sindicalismo-dialogo-social\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/albergueweb1.uva.es\/catedra-sindicalismo-dialogo-social\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/albergueweb1.uva.es\/catedra-sindicalismo-dialogo-social\/index.php\/wp-json\/wp\/v2\/comments?post=4407"}],"version-history":[{"count":1,"href":"https:\/\/albergueweb1.uva.es\/catedra-sindicalismo-dialogo-social\/index.php\/wp-json\/wp\/v2\/posts\/4407\/revisions"}],"predecessor-version":[{"id":4410,"href":"https:\/\/albergueweb1.uva.es\/catedra-sindicalismo-dialogo-social\/index.php\/wp-json\/wp\/v2\/posts\/4407\/revisions\/4410"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/albergueweb1.uva.es\/catedra-sindicalismo-dialogo-social\/index.php\/wp-json\/wp\/v2\/media\/4408"}],"wp:attachment":[{"href":"https:\/\/albergueweb1.uva.es\/catedra-sindicalismo-dialogo-social\/index.php\/wp-json\/wp\/v2\/media?parent=4407"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/albergueweb1.uva.es\/catedra-sindicalismo-dialogo-social\/index.php\/wp-json\/wp\/v2\/categories?post=4407"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/albergueweb1.uva.es\/catedra-sindicalismo-dialogo-social\/index.php\/wp-json\/wp\/v2\/tags?post=4407"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}